{"id":34,"count":1,"description":"","link":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/category\/kreative-ideen-und-anleitungen\/anleitungen-karten\/","name":"Anleitungen Karten basteln","slug":"anleitungen-karten","taxonomy":"category","parent":389,"meta":[],"_links":{"self":[{"href":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/wp-json\/wp\/v2\/categories\/34"}],"collection":[{"href":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/wp-json\/wp\/v2\/categories\/389"}],"wp:post_type":[{"href":"http:\/\/www.nicis-kreative-inspirationen.de\/blog\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}